{"id":9199,"date":"2022-04-04T20:27:45","date_gmt":"2022-04-04T18:27:45","guid":{"rendered":"https:\/\/emoble.es\/cubreradiadores\/sella\/"},"modified":"2022-04-04T20:27:45","modified_gmt":"2022-04-04T18:27:45","slug":"sella","status":"publish","type":"cubreradiadores","link":"https:\/\/emoble.es\/fr\/sella\/","title":{"rendered":"Sella"},"content":{"rendered":"<p>Le cache-radiateur Sella harmonise le m\u00e9tal et le bois avec des \u00e9quilibres spectaculaires entre les finitions choisies. Il dispose d&rsquo;un plateau coulissant pratique avec espace de rangement. C&rsquo;est un meuble qui enchante dans les maisons les plus avant-gardistes.<\/p>\n<p>Ce cache-radiateur a un corps partiellement m\u00e9tallique, les diff\u00e9rentes parties du corps sont reli\u00e9es entre elles par une grille en acier perfor\u00e9e qui permet la circulation de l&rsquo;air. Les diff\u00e9rentes parties du corps sont en MDF haute densit\u00e9 que nous pouvons laquer dans les 210 coloris de la gamme RAL ou placage dans 10 essences de bois diff\u00e9rentes. Le plateau coulissant, o\u00f9 se trouve un petit trou qui fait office de tiroir, est en acier laqu\u00e9.<\/p>\n<p>Ce cache-radiateur est fabriqu\u00e9 sur mesure apr\u00e8s \u00e9valuation par notre \u00e9quipe technique. Selon les mesures et la finition, il a un prix diff\u00e9rent.<\/p>\n<p>Tous nos meubles sont fabriqu\u00e9s une fois la finition choisie, nous n&rsquo;avons pas de stock. Nous fabriquons chaque meuble individuellement sur commande et tous les mat\u00e9riaux que nous utilisons sont acquis et transform\u00e9s en Espagne. Notre d\u00e9lai de livraison est de 40 jours ouvrables.<\/p>\n","protected":false},"featured_media":7629,"template":"","meta":{"inline_featured_image":false,"ngg_post_thumbnail":0},"categorias":[56],"class_list":["post-9199","cubreradiadores","type-cubreradiadores","status-publish","has-post-thumbnail","hentry","categorias-cubreradiadores-diseno-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sella - Emoble<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emoble.es\/fr\/sella\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sella - Emoble\" \/>\n<meta property=\"og:description\" content=\"Le cache-radiateur Sella harmonise le m\u00e9tal et le bois avec des \u00e9quilibres spectaculaires entre les finitions choisies. Il dispose d&rsquo;un plateau coulissant pratique avec espace de rangement. C&rsquo;est un meuble qui enchante dans les maisons les plus avant-gardistes. Ce cache-radiateur a un corps partiellement m\u00e9tallique, les diff\u00e9rentes parties du corps sont reli\u00e9es entre elles par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emoble.es\/fr\/sella\/\" \/>\n<meta property=\"og:site_name\" content=\"Emoble\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/\",\"url\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/\",\"name\":\"Sella - Emoble\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emoble.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PRODUCTO-11-FOTO-1-Cubreradiador-Sella-Emoble.jpg\",\"datePublished\":\"2022-04-04T18:27:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emoble.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PRODUCTO-11-FOTO-1-Cubreradiador-Sella-Emoble.jpg\",\"contentUrl\":\"https:\\\/\\\/emoble.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PRODUCTO-11-FOTO-1-Cubreradiador-Sella-Emoble.jpg\",\"width\":1030,\"height\":696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/sella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/emoble.es\\\/fr\\\/couvertures-de-radiateur-personnalisees-en-ligne-emoble-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cubreradiadores\",\"item\":\"https:\\\/\\\/emoble.es\\\/fr\\\/cubreradiadores\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/emoble.es\\\/fr\\\/\",\"name\":\"Emoble\",\"description\":\"Cubreradiadores a medida online - Emoble.es\",\"publisher\":{\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emoble.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/#organization\",\"name\":\"Emoble\",\"url\":\"https:\\\/\\\/emoble.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/emoble.es\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/emoble_logo_positivo.svg\",\"contentUrl\":\"https:\\\/\\\/emoble.es\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/emoble_logo_positivo.svg\",\"width\":486,\"height\":186,\"caption\":\"Emoble\"},\"image\":{\"@id\":\"https:\\\/\\\/emoble.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sella - Emoble","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emoble.es\/fr\/sella\/","og_locale":"fr_FR","og_type":"article","og_title":"Sella - Emoble","og_description":"Le cache-radiateur Sella harmonise le m\u00e9tal et le bois avec des \u00e9quilibres spectaculaires entre les finitions choisies. Il dispose d&rsquo;un plateau coulissant pratique avec espace de rangement. C&rsquo;est un meuble qui enchante dans les maisons les plus avant-gardistes. Ce cache-radiateur a un corps partiellement m\u00e9tallique, les diff\u00e9rentes parties du corps sont reli\u00e9es entre elles par [&hellip;]","og_url":"https:\/\/emoble.es\/fr\/sella\/","og_site_name":"Emoble","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emoble.es\/fr\/sella\/","url":"https:\/\/emoble.es\/fr\/sella\/","name":"Sella - Emoble","isPartOf":{"@id":"https:\/\/emoble.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emoble.es\/fr\/sella\/#primaryimage"},"image":{"@id":"https:\/\/emoble.es\/fr\/sella\/#primaryimage"},"thumbnailUrl":"https:\/\/emoble.es\/wp-content\/uploads\/2022\/04\/PRODUCTO-11-FOTO-1-Cubreradiador-Sella-Emoble.jpg","datePublished":"2022-04-04T18:27:45+00:00","breadcrumb":{"@id":"https:\/\/emoble.es\/fr\/sella\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emoble.es\/fr\/sella\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emoble.es\/fr\/sella\/#primaryimage","url":"https:\/\/emoble.es\/wp-content\/uploads\/2022\/04\/PRODUCTO-11-FOTO-1-Cubreradiador-Sella-Emoble.jpg","contentUrl":"https:\/\/emoble.es\/wp-content\/uploads\/2022\/04\/PRODUCTO-11-FOTO-1-Cubreradiador-Sella-Emoble.jpg","width":1030,"height":696},{"@type":"BreadcrumbList","@id":"https:\/\/emoble.es\/fr\/sella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/emoble.es\/fr\/couvertures-de-radiateur-personnalisees-en-ligne-emoble-es\/"},{"@type":"ListItem","position":2,"name":"Cubreradiadores","item":"https:\/\/emoble.es\/fr\/cubreradiadores\/"},{"@type":"ListItem","position":3,"name":"Sella"}]},{"@type":"WebSite","@id":"https:\/\/emoble.es\/fr\/#website","url":"https:\/\/emoble.es\/fr\/","name":"Emoble","description":"Cubreradiadores a medida online - Emoble.es","publisher":{"@id":"https:\/\/emoble.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emoble.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/emoble.es\/fr\/#organization","name":"Emoble","url":"https:\/\/emoble.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emoble.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/emoble.es\/wp-content\/uploads\/2022\/03\/emoble_logo_positivo.svg","contentUrl":"https:\/\/emoble.es\/wp-content\/uploads\/2022\/03\/emoble_logo_positivo.svg","width":486,"height":186,"caption":"Emoble"},"image":{"@id":"https:\/\/emoble.es\/fr\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/cubreradiadores\/9199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/cubreradiadores"}],"about":[{"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/types\/cubreradiadores"}],"version-history":[{"count":0,"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/cubreradiadores\/9199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/media\/7629"}],"wp:attachment":[{"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/media?parent=9199"}],"wp:term":[{"taxonomy":"categorias","embeddable":true,"href":"https:\/\/emoble.es\/fr\/wp-json\/wp\/v2\/categorias?post=9199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}